{"id":2696,"date":"2016-06-09T08:42:34","date_gmt":"2016-06-09T08:42:34","guid":{"rendered":"https:\/\/www.vfgstrade.com\/city-of-iglesias\/"},"modified":"2021-03-26T09:30:21","modified_gmt":"2021-03-26T09:30:21","slug":"city-of-iglesias","status":"publish","type":"post","link":"https:\/\/www.vfgstrade.com\/de\/city-of-iglesias\/","title":{"rendered":"City of Iglesias"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]<\/p>\n<div id=\"attachment_1306\" class=\"wp-caption alignnone\">\n<p>Supply and installation of automatic retractable bollard.<\/p>\n<\/div>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row css_margin=&#8220;-50::::-50:::::::::::&#8220;][vc_column][rdy_gallery gutter=&#8220;5&#8243; images=&#8220;1324,1325&#8243;][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text] Supply and installation of automatic retractable bollard. [\/vc_column_text][\/vc_column][\/vc_row][vc_row css_margin=&#8220;-50::::-50:::::::::::&#8220;][vc_column][rdy_gallery gutter=&#8220;5&#8243; images=&#8220;1324,1325&#8243;][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":1,"featured_media":2697,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"wds_primary_category":0,"footnotes":""},"categories":[],"tags":[],"class_list":["post-2696","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>VFG Strade srl: fornitura e posa in opera di segnaletica stradale orizzontale e verticale, di barriere stradali e fonoassorbenti, della manutenzione di piazzali e aree verdi<\/title>\n<meta name=\"description\" content=\"VFG Strade Srl nasce nel 2005, dalla decennale esperienza di tecnici e professionisti, che hanno scelto di mettere le loro competenze e la loro professionalit\u00e0 a disposizione di enti pubblici e privati.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vfgstrade.com\/comune-di-iglesias-ci\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"VFG Strade srl: fornitura e posa in opera di segnaletica stradale orizzontale e verticale, di barriere stradali e fonoassorbenti, della manutenzione di piazzali e aree verdi\" \/>\n<meta property=\"og:description\" content=\"VFG Strade Srl nasce nel 2005, dalla decennale esperienza di tecnici e professionisti, che hanno scelto di mettere le loro competenze e la loro professionalit\u00e0 a disposizione di enti pubblici e privati.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vfgstrade.com\/comune-di-iglesias-ci\/\" \/>\n<meta property=\"og:site_name\" content=\"VFG strade\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/vfgstrade\" \/>\n<meta property=\"article:published_time\" content=\"2016-06-09T08:42:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-26T09:30:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vfgstrade.com\/wp-content\/uploads\/2016\/06\/Iglesias-Dissuasore-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.vfgstrade.com\\\/comune-di-iglesias-ci\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vfgstrade.com\\\/comune-di-iglesias-ci\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.vfgstrade.com\\\/en\\\/#\\\/schema\\\/person\\\/36df81f5868d7d3a3616df3ff0cdb991\"},\"headline\":\"City of Iglesias\",\"datePublished\":\"2016-06-09T08:42:34+00:00\",\"dateModified\":\"2021-03-26T09:30:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.vfgstrade.com\\\/comune-di-iglesias-ci\\\/\"},\"wordCount\":40,\"publisher\":{\"@id\":\"https:\\\/\\\/www.vfgstrade.com\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vfgstrade.com\\\/comune-di-iglesias-ci\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vfgstrade.com\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/Iglesias-Dissuasore-2.png\",\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vfgstrade.com\\\/comune-di-iglesias-ci\\\/\",\"url\":\"https:\\\/\\\/www.vfgstrade.com\\\/comune-di-iglesias-ci\\\/\",\"name\":\"VFG Strade srl: fornitura e posa in opera di segnaletica stradale orizzontale e verticale, di barriere stradali e fonoassorbenti, della manutenzione di piazzali e aree verdi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vfgstrade.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vfgstrade.com\\\/comune-di-iglesias-ci\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vfgstrade.com\\\/comune-di-iglesias-ci\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vfgstrade.com\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/Iglesias-Dissuasore-2.png\",\"datePublished\":\"2016-06-09T08:42:34+00:00\",\"dateModified\":\"2021-03-26T09:30:21+00:00\",\"description\":\"VFG Strade Srl nasce nel 2005, dalla decennale esperienza di tecnici e professionisti, che hanno scelto di mettere le loro competenze e la loro professionalit\u00e0 a disposizione di enti pubblici e privati.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vfgstrade.com\\\/comune-di-iglesias-ci\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vfgstrade.com\\\/comune-di-iglesias-ci\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.vfgstrade.com\\\/comune-di-iglesias-ci\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vfgstrade.com\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/Iglesias-Dissuasore-2.png\",\"contentUrl\":\"https:\\\/\\\/www.vfgstrade.com\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/Iglesias-Dissuasore-2.png\",\"width\":480,\"height\":640,\"caption\":\"Retractable bollard in Iglesias\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vfgstrade.com\\\/comune-di-iglesias-ci\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.vfgstrade.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"City of Iglesias\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vfgstrade.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.vfgstrade.com\\\/en\\\/\",\"name\":\"VFG strade\",\"description\":\"Lavori stradali - Segnaletica stradale\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vfgstrade.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vfgstrade.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vfgstrade.com\\\/en\\\/#organization\",\"name\":\"VFG strade\",\"url\":\"https:\\\/\\\/www.vfgstrade.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.vfgstrade.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vfgstrade.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/cropped-icona_sito_vfg_strade.png\",\"contentUrl\":\"https:\\\/\\\/www.vfgstrade.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/cropped-icona_sito_vfg_strade.png\",\"width\":512,\"height\":512,\"caption\":\"VFG strade\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vfgstrade.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/vfgstrade\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/5264177\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.vfgstrade.com\\\/en\\\/#\\\/schema\\\/person\\\/36df81f5868d7d3a3616df3ff0cdb991\",\"name\":\"admin\",\"url\":\"https:\\\/\\\/www.vfgstrade.com\\\/de\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"VFG Strade srl: fornitura e posa in opera di segnaletica stradale orizzontale e verticale, di barriere stradali e fonoassorbenti, della manutenzione di piazzali e aree verdi","description":"VFG Strade Srl nasce nel 2005, dalla decennale esperienza di tecnici e professionisti, che hanno scelto di mettere le loro competenze e la loro professionalit\u00e0 a disposizione di enti pubblici e privati.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vfgstrade.com\/comune-di-iglesias-ci\/","og_locale":"de_DE","og_type":"article","og_title":"VFG Strade srl: fornitura e posa in opera di segnaletica stradale orizzontale e verticale, di barriere stradali e fonoassorbenti, della manutenzione di piazzali e aree verdi","og_description":"VFG Strade Srl nasce nel 2005, dalla decennale esperienza di tecnici e professionisti, che hanno scelto di mettere le loro competenze e la loro professionalit\u00e0 a disposizione di enti pubblici e privati.","og_url":"https:\/\/www.vfgstrade.com\/comune-di-iglesias-ci\/","og_site_name":"VFG strade","article_publisher":"https:\/\/www.facebook.com\/vfgstrade","article_published_time":"2016-06-09T08:42:34+00:00","article_modified_time":"2021-03-26T09:30:21+00:00","og_image":[{"width":480,"height":640,"url":"https:\/\/www.vfgstrade.com\/wp-content\/uploads\/2016\/06\/Iglesias-Dissuasore-2.png","type":"image\/png"}],"author":"admin","twitter_misc":{"Verfasst von":"admin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vfgstrade.com\/comune-di-iglesias-ci\/#article","isPartOf":{"@id":"https:\/\/www.vfgstrade.com\/comune-di-iglesias-ci\/"},"author":{"name":"admin","@id":"https:\/\/www.vfgstrade.com\/en\/#\/schema\/person\/36df81f5868d7d3a3616df3ff0cdb991"},"headline":"City of Iglesias","datePublished":"2016-06-09T08:42:34+00:00","dateModified":"2021-03-26T09:30:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vfgstrade.com\/comune-di-iglesias-ci\/"},"wordCount":40,"publisher":{"@id":"https:\/\/www.vfgstrade.com\/en\/#organization"},"image":{"@id":"https:\/\/www.vfgstrade.com\/comune-di-iglesias-ci\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vfgstrade.com\/wp-content\/uploads\/2016\/06\/Iglesias-Dissuasore-2.png","inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.vfgstrade.com\/comune-di-iglesias-ci\/","url":"https:\/\/www.vfgstrade.com\/comune-di-iglesias-ci\/","name":"VFG Strade srl: fornitura e posa in opera di segnaletica stradale orizzontale e verticale, di barriere stradali e fonoassorbenti, della manutenzione di piazzali e aree verdi","isPartOf":{"@id":"https:\/\/www.vfgstrade.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vfgstrade.com\/comune-di-iglesias-ci\/#primaryimage"},"image":{"@id":"https:\/\/www.vfgstrade.com\/comune-di-iglesias-ci\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vfgstrade.com\/wp-content\/uploads\/2016\/06\/Iglesias-Dissuasore-2.png","datePublished":"2016-06-09T08:42:34+00:00","dateModified":"2021-03-26T09:30:21+00:00","description":"VFG Strade Srl nasce nel 2005, dalla decennale esperienza di tecnici e professionisti, che hanno scelto di mettere le loro competenze e la loro professionalit\u00e0 a disposizione di enti pubblici e privati.","breadcrumb":{"@id":"https:\/\/www.vfgstrade.com\/comune-di-iglesias-ci\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vfgstrade.com\/comune-di-iglesias-ci\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.vfgstrade.com\/comune-di-iglesias-ci\/#primaryimage","url":"https:\/\/www.vfgstrade.com\/wp-content\/uploads\/2016\/06\/Iglesias-Dissuasore-2.png","contentUrl":"https:\/\/www.vfgstrade.com\/wp-content\/uploads\/2016\/06\/Iglesias-Dissuasore-2.png","width":480,"height":640,"caption":"Retractable bollard in Iglesias"},{"@type":"BreadcrumbList","@id":"https:\/\/www.vfgstrade.com\/comune-di-iglesias-ci\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.vfgstrade.com\/"},{"@type":"ListItem","position":2,"name":"City of Iglesias"}]},{"@type":"WebSite","@id":"https:\/\/www.vfgstrade.com\/en\/#website","url":"https:\/\/www.vfgstrade.com\/en\/","name":"VFG strade","description":"Lavori stradali - Segnaletica stradale","publisher":{"@id":"https:\/\/www.vfgstrade.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vfgstrade.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.vfgstrade.com\/en\/#organization","name":"VFG strade","url":"https:\/\/www.vfgstrade.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.vfgstrade.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.vfgstrade.com\/wp-content\/uploads\/2021\/03\/cropped-icona_sito_vfg_strade.png","contentUrl":"https:\/\/www.vfgstrade.com\/wp-content\/uploads\/2021\/03\/cropped-icona_sito_vfg_strade.png","width":512,"height":512,"caption":"VFG strade"},"image":{"@id":"https:\/\/www.vfgstrade.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/vfgstrade","https:\/\/www.linkedin.com\/company\/5264177\/"]},{"@type":"Person","@id":"https:\/\/www.vfgstrade.com\/en\/#\/schema\/person\/36df81f5868d7d3a3616df3ff0cdb991","name":"admin","url":"https:\/\/www.vfgstrade.com\/de\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.vfgstrade.com\/de\/wp-json\/wp\/v2\/posts\/2696","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vfgstrade.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vfgstrade.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vfgstrade.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vfgstrade.com\/de\/wp-json\/wp\/v2\/comments?post=2696"}],"version-history":[{"count":1,"href":"https:\/\/www.vfgstrade.com\/de\/wp-json\/wp\/v2\/posts\/2696\/revisions"}],"predecessor-version":[{"id":2698,"href":"https:\/\/www.vfgstrade.com\/de\/wp-json\/wp\/v2\/posts\/2696\/revisions\/2698"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vfgstrade.com\/de\/wp-json\/wp\/v2\/media\/2697"}],"wp:attachment":[{"href":"https:\/\/www.vfgstrade.com\/de\/wp-json\/wp\/v2\/media?parent=2696"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vfgstrade.com\/de\/wp-json\/wp\/v2\/categories?post=2696"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vfgstrade.com\/de\/wp-json\/wp\/v2\/tags?post=2696"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}